{"id":5373,"count":1,"description":"","link":"https:\/\/kyivyes.com.ua\/ru\/tag\/podgotovka","name":"\u043f\u043e\u0434\u0433\u043e\u0442\u043e\u0432\u043a\u0430","slug":"podgotovka","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/kyivyes.com.ua\/ru\/wp-json\/wp\/v2\/tags\/5373","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kyivyes.com.ua\/ru\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/kyivyes.com.ua\/ru\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/kyivyes.com.ua\/ru\/wp-json\/wp\/v2\/posts?tags=5373"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}